{"id":2222,"count":1,"description":"","link":"https:\/\/birminghamka.com\/en\/t\/aston-hall-proposal","name":"Aston Hall proposal","slug":"aston-hall-proposal","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/birminghamka.com\/en\/wp-json\/wp\/v2\/tags\/2222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/birminghamka.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/birminghamka.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/birminghamka.com\/en\/wp-json\/wp\/v2\/posts?tags=2222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}